{"id":81735,"date":"2024-12-09T19:43:03","date_gmt":"2024-12-09T22:43:03","guid":{"rendered":"http:\/\/portalcatolico.net\/portal\/?p=81735"},"modified":"2024-12-09T19:43:03","modified_gmt":"2024-12-09T22:43:03","slug":"papa-francisco-a-mulher-nao-e-um-ser-humano-de-segunda-categoria","status":"publish","type":"post","link":"https:\/\/portalcatolico.net\/portal\/papa-francisco-a-mulher-nao-e-um-ser-humano-de-segunda-categoria\/","title":{"rendered":"Papa Francisco: a mulher n\u00e3o \u00e9 um ser humano de segunda categoria"},"content":{"rendered":"<p>&#8220;N\u00f3s estamos acostumados a essa cultura machista, a ver a mulher, n\u00e3o digo como o cachorrinho ou o gato de casa, mas como um ser humano de segunda categoria&#8221;, afirmou o Pont\u00edfice a volunt\u00e1rios de &#8220;Manos Unidas&#8221;. Francisco enalteceu a figura da mulher, que tanto ajudou na cria\u00e7\u00e3o da ONG da Igreja Cat\u00f3lica h\u00e1 65 anos, uma associa\u00e7\u00e3o espanhola que trabalha no combate \u00e0 fome, ao subdesenvolvimento e \u00e0 falta de instru\u00e7\u00e3o nos pa\u00edses da Am\u00e9rica, \u00c1frica e \u00c1sia.<\/p>\n<p>O Papa Francisco recebeu na manh\u00e3 desta segunda-feira (09\/12), no Vaticano, uma delega\u00e7\u00e3o do Comit\u00ea Cat\u00f3lico da Campanha contra a Fome Mundial de &#8220;Manos Unidas&#8221;, uma Organiza\u00e7\u00e3o N\u00e3o Governamental da Espanha que h\u00e1 65 anos contribui para a promo\u00e7\u00e3o e o progresso dos pa\u00edses em desenvolvimento.&nbsp;Segundo dados da pr\u00f3pria ONG do in\u00edcio de dezembro, mais de 1 milh\u00e3o de pessoas na \u00c1merica, na \u00c1frica e na \u00c1sia j\u00e1 conseguiram mudar de vida com a generosidade e a dedica\u00e7\u00e3o de uma rede solid\u00e1ria de 6.500 volunt\u00e1rios, mas a campanha, segundo contou Francisco em discurso em espanhol, alcan\u00e7a &#8220;somente 15% daqueles que sofrem a fome do mundo. \u00c9 muito dif\u00edcil, muito dif\u00edcil&#8221;.<\/p>\n<p><strong>A mulher leva o mundo adiante<\/strong><\/p>\n<p>O Pont\u00edfice recordou que a associa\u00e7\u00e3o nasceu como &#8220;resposta das mulheres da A\u00e7\u00e3o Cat\u00f3lica da Espanha ao apelo da FAO, que denunciava a &#8216;fome de p\u00e3o, fome de cultura e fome de Deus que aflige grande parte da humanidade'&#8221;. Uma pequena rede de mulheres formada em 1959 que hoje cresceu e se converteu em ONG devido \u00e0 &#8220;sensibilidade e for\u00e7a pr\u00f3prias do g\u00eanio feminino&#8221;, comentou o Papa, fazendo liga\u00e7\u00e3o &#8220;\u00e0 figura da M\u00e3e de Deus, que celebramos na sua Imaculada Concei\u00e7\u00e3o. Pois a Virgem Maria \u00e9 a&nbsp;<i>Mulher<\/i>&nbsp;por excel\u00eancia&#8221;.&nbsp;<\/p>\n<p><i>&#8220;N\u00f3s estamos acostumados a essa cultura machista, a ver a mulher, n\u00e3o digo como o cachorrinho ou o gato de casa, mas como um ser humano de segunda categoria. E n\u00e3o vamos nos esquecer que s\u00e3o as mulheres a levar o mundo adiante e &#8211; como alguns dizem &#8211; s\u00e3o elas que comandam. Mas tudo bem. Mas \u00e9 a mulher que leva adiante a fam\u00edlia, que leva adiante os povos, que se aproxima das necessidades, aquela sensibilidade t\u00e3o rica da mulher.&#8221;<\/i><\/p>\n<p>Maria, continuou Francisco, que \u00e9 &#8220;atenta \u00e0s necessidades dos seus filhos&#8221;, serve de &#8220;<i>modelo plenamente realizado<\/i>&#8221; para a humanidade. Assim como t\u00eam feito as m\u00e3es, filhas, esposas e sogras da associa\u00e7\u00e3o p\u00fablica de fi\u00e9is da Igreja Cat\u00f3lica&nbsp;&#8220;Manos Unidas&#8221; que seguem a miss\u00e3o de &#8220;combater a fome, o subdesenvolvimento e a falta de instru\u00e7\u00e3o&#8221;. E o Papa dividiu uma anedota:<\/p>\n<p><i>Ursula Von der Layen, a presidente do Conselho da Europa, \u00e9 m\u00e9dica e m\u00e3e de 7 filhos. Um dia eu lhe disse &#8211; ap\u00f3s ter resolvido um problema muito dif\u00edcil com a B\u00e9lgica, a Holanda e muito dinheiro, e ela o resolveu bem &#8211; e eu lhe disse: &#8216;senhora &#8211; est\u00e1vamos sentados ali &#8211; como fez para resolv\u00ea-lo?&#8217; E ela come\u00e7ou a fazer assim com as m\u00e3os (no sentido de equilibrar tudo). &#8216;Como fazemos n\u00f3s, m\u00e3es&#8217;. A mulher tem talento, o g\u00eanio feminino.<\/i><\/p>\n<p><strong>A dignidade de ser filho de Deus<\/strong><\/p>\n<p>E o Papa Francisco finalizou o discurso, encorajando a prosseguir com o trabalho volunt\u00e1rio e de assist\u00eancia &#8220;na constru\u00e7\u00e3o da civiliza\u00e7\u00e3o do amor&#8221;:<\/p>\n<p><i>&#8220;Ao nos aproximarmos do Jubileu de 2025, convido-os a serem peregrinos de esperan\u00e7a e a reorientar a vida para Jesus, tamb\u00e9m por meio da contribui\u00e7\u00e3o de voc\u00eas para a melhoria material, o progresso moral e o desenvolvimento espiritual dos mais fr\u00e1geis e necessitados, para ajud\u00e1-los a obter uma vida que corresponda \u00e0 dignidade deles de filhos de Deus.&#8221;<\/i><\/p>\n<p><b>Andressa Collet &#8211; Vatican News<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;N\u00f3s estamos acostumados a essa cultura machista, a ver a mulher, n\u00e3o digo como o cachorrinho ou o gato de casa, mas como um ser humano de segunda categoria&#8221;, afirmou o Pont\u00edfice a volunt\u00e1rios de &#8220;Manos Unidas&#8221;. Francisco enalteceu a figura da mulher, que tanto ajudou na cria\u00e7\u00e3o da ONG da Igreja Cat\u00f3lica h\u00e1 65&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"https:\/\/portalcatolico.net\/portal\/papa-francisco-a-mulher-nao-e-um-ser-humano-de-segunda-categoria\/\">Continue Reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":81736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-81735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-igreja_no_mundo"],"_links":{"self":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/81735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/comments?post=81735"}],"version-history":[{"count":1,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/81735\/revisions"}],"predecessor-version":[{"id":81737,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/81735\/revisions\/81737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/media\/81736"}],"wp:attachment":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/media?parent=81735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/categories?post=81735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/tags?post=81735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}