{"id":81715,"date":"2024-12-03T21:48:04","date_gmt":"2024-12-04T00:48:04","guid":{"rendered":"http:\/\/portalcatolico.net\/portal\/?p=81715"},"modified":"2024-12-03T21:48:49","modified_gmt":"2024-12-04T00:48:49","slug":"diocese-de-itabuna-ganha-mais-uma-paroquia-confira","status":"publish","type":"post","link":"https:\/\/portalcatolico.net\/portal\/diocese-de-itabuna-ganha-mais-uma-paroquia-confira\/","title":{"rendered":"Diocese de Itabuna ganha mais uma par\u00f3quia. Confira!"},"content":{"rendered":"<p><span class=\"v1PlainText\" dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-81718\" src=\"http:\/\/portalcatolico.net\/portal\/wp-content\/uploads\/2024\/12\/sao-francico03012-300x166.png\" alt=\"\" width=\"831\" height=\"460\" srcset=\"https:\/\/portalcatolico.net\/portal\/wp-content\/uploads\/2024\/12\/sao-francico03012-300x166.png 300w, https:\/\/portalcatolico.net\/portal\/wp-content\/uploads\/2024\/12\/sao-francico03012-768x426.png 768w, https:\/\/portalcatolico.net\/portal\/wp-content\/uploads\/2024\/12\/sao-francico03012.png 850w\" sizes=\"auto, (max-width: 831px) 100vw, 831px\" \/>Foi em clima de festa que a Comunidade S\u00e3o Francisco de Assis, localizada no Distrito de Rio do Meio, foi elevada a mais nova Par\u00f3quia da Diocese de Itabuna (BA). Com a igreja repleta de fi\u00e9is, a celebra\u00e7\u00e3o, realizada na noite de ter\u00e7a-feira, 03\/12, foi cercada por muita ora\u00e7\u00e3o, emo\u00e7\u00e3o e alegria.&nbsp;A participa\u00e7\u00e3o dos fi\u00e9is foi massiva. Todos estavam ansiosos por este momento hist\u00f3rico, afinal foram dois anos e sete meses de&nbsp;evangeliza\u00e7\u00e3o e prepara\u00e7\u00e3o com as pastorais e movimentos.<\/span><\/p>\n<div class=\"v1PlainText\" dir=\"auto\">&nbsp;<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">A programa\u00e7\u00e3o especial da instala\u00e7\u00e3o da trig\u00e9sima quinta par\u00f3quia da Diocese de Itabuna, situada na Forania Norte, foi&nbsp;criada a partir do desmembramento da Matriz de Santo Ant\u00f4nio de Itoror\u00f3 e marcada pela nomea\u00e7\u00e3o do padre Jos\u00e9 Augusto, como o primeiro Administrador paroquial. A comunidade cat\u00f3lica do distrito do Rio do&nbsp;Meio agora \u00e9 sede paroquial de Santa Francisco de Assis.<br \/>\nA noite foi celebrada por uma multid\u00e3o de fieis de v\u00e1rias par\u00f3quias de Itabuna e de cidades circunvizinhas.&nbsp;<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">&nbsp;<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">A missa de instala\u00e7\u00e3o da nova par\u00f3quia foi presidida pelo Administrador Apost\u00f3lico da Diocese de Itabuna e bispo da diocese de Teixeira de Freitas\/Caravelas no Extremo Sul da Bahia, Dom Jailton de Oliveira Lino. Na ocasi\u00e3o, ele destacou:&nbsp;&#8220;Gostaria de dizer que a Par\u00f3quia S\u00e3o Francisco de Assis n\u00e3o est\u00e1 se separando da Par\u00f3quia de Itoror\u00f3. N\u00f3s, como Igreja, n\u00e3o nos separamos. N\u00f3s apenas, reordenamos, reorganizamos. Somos a mesma equipe! Para mim \u00e9 uma alegria muito grande estar aqui com voc\u00eas, criando esta par\u00f3quia!&#8221;, disse o bispo.<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">&nbsp;<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">A concelebra\u00e7\u00e3o ficou por&nbsp;conta de padres e di\u00e1conos das tr\u00eas Foranias: Centro, Norte e Sul.<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">&nbsp;<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">\n<p>O decreto de cria\u00e7\u00e3o da par\u00f3quia foi lido pelo Vig\u00e1rio Episcopal e p\u00e1roco da par\u00f3quia Senhor Deus Menino de Ibicara\u00ed, o Pe. Wesley Concei\u00e7\u00e3o do Carmo.<\/p>\n<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">\n<p>O prefeito da cidade, vereadores e secret\u00e1rios, se fizeram presentes na cerim\u00f4nia.<\/p>\n<p>A eleva\u00e7\u00e3o da comunidade \u00e0 par\u00f3quia se deu, ap\u00f3s o Bispo Diocesano ouvir o parecer favor\u00e1vel do Col\u00e9gio dos Consultores e do Conselho Presbiteral. A iniciativa visa um melhor atendimento espiritual e pastoral do Povo de Deus.<\/p>\n<p>Al\u00e9m da eleva\u00e7\u00e3o \u00e0 Par\u00f3quia, a celebra\u00e7\u00e3o contou, ainda, com os ritos de posse do primeiro Administrador Paroquial, Padre Jos\u00e9 Augusto Ferreira Silva. Ap\u00f3s a leitura da provis\u00e3o can\u00f4nica, o sacerdote fez a profiss\u00e3o de f\u00e9 e, tocando o Evangelho, fez seu juramento de fidelidade. Ele tamb\u00e9m demonstrou alegria por ter recebido o apoio de muitas pessoas e&nbsp;fez diversos agradecimentos: &#8220;Quero agradecer a todos voc\u00eas, desde a organiza\u00e7\u00e3o das primeiras reuni\u00f5es quando aqui era pra ser Quase-Par\u00f3quia. \u00c9 uma alegria muito grande depois de dois anos e sete meses de caminhada, de organiza\u00e7\u00e3o, de encontros, de forma\u00e7\u00e3o, podermos hoje dizer que aquela Quase-Par\u00f3quia hoje \u00e9 Par\u00f3quia S\u00e3o Francisco de Assis!&#8221;.&nbsp;<\/p>\n<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">&nbsp;<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">&nbsp;<\/div>\n<div class=\"v1PlainText\" dir=\"auto\">\n<div class=\"v1PlainText\" dir=\"auto\">Tudo come\u00e7ou no dia 3 de maio de 2022, quando o padre Jos\u00e9 Augusto Ferreira Silva foi recebido em Rio do Meio, distrito de Itoror\u00f3 (BA), em grande<br \/>\nestilo! As comunidades que comp\u00f5em a Quase-Par\u00f3quia S\u00e3o Francisco de Assis se reuniram na entrada do distrito para recepcionar o seu novo<br \/>\npastor. Na oportunidade, foi realizada uma caminhada, junto com o Pe. Augusto, at\u00e9 a Igreja, onde<br \/>\naconteceu a celebra\u00e7\u00e3o de nomea\u00e7\u00e3o e a cria\u00e7\u00e3o da Quase-Par\u00f3quia S\u00e3o Francisco de Assis de Rio do Meio de Itoror\u00f3.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foi em clima de festa que a Comunidade S\u00e3o Francisco de Assis, localizada no Distrito de Rio do Meio, foi elevada a mais nova Par\u00f3quia da Diocese de Itabuna (BA). Com a igreja repleta de fi\u00e9is, a celebra\u00e7\u00e3o, realizada na noite de ter\u00e7a-feira, 03\/12, foi cercada por muita ora\u00e7\u00e3o, emo\u00e7\u00e3o e alegria.&nbsp;A participa\u00e7\u00e3o dos fi\u00e9is&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"https:\/\/portalcatolico.net\/portal\/diocese-de-itabuna-ganha-mais-uma-paroquia-confira\/\">Continue Reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":81716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[68],"tags":[],"class_list":["post-81715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homilias"],"_links":{"self":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/81715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/comments?post=81715"}],"version-history":[{"count":2,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/81715\/revisions"}],"predecessor-version":[{"id":81719,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/81715\/revisions\/81719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/media\/81716"}],"wp:attachment":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/media?parent=81715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/categories?post=81715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/tags?post=81715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}