{"id":15440,"date":"2017-01-07T20:53:38","date_gmt":"2017-01-07T20:53:38","guid":{"rendered":"http:\/\/portalcatolico.net\/portal\/?p=15440"},"modified":"2017-01-07T20:55:34","modified_gmt":"2017-01-07T20:55:34","slug":"padre-gianfranco-encarceramento-em-massa-e-comercializacao-do-carcere-sao-os-principais-problemas","status":"publish","type":"post","link":"https:\/\/portalcatolico.net\/portal\/padre-gianfranco-encarceramento-em-massa-e-comercializacao-do-carcere-sao-os-principais-problemas\/","title":{"rendered":"Padre Gianfranco: Encarceramento em massa e comercializa\u00e7\u00e3o do c\u00e1rcere s\u00e3o os principais problemas"},"content":{"rendered":"<p style=\"text-align: justify;\">A morte de 56 presos no Complexo Penitenci\u00e1rio An\u00edsio Jobim, em Manaus (AM), no primeiro dia do ano, resultado de um dos maiores motins da hist\u00f3ria do sistema prisional brasileiro, gerou perplexidade em boa parte da sociedade brasileira.<\/p>\n<p style=\"text-align: justify;\">Infelizmente, o que se viu em Manaus acontece de forma recorrente pelo pa\u00eds: morte de presos quase que diariamente nas unidades prisionais brasileiras, como h\u00e1 tempos denuncia a Pastoral Carcer\u00e1ria Nacional. Para comentar o caos do sistema prisional no pa\u00eds, o Padre Gianfranco Graziola, vice-coordenador nacional da Pastoral, concedeu entrevista \u00e0 R\u00e1dio Vaticano, em que denunciou o fen\u00f4meno do encarceramento em massa e a comercializa\u00e7\u00e3o do sistema carcer\u00e1rio brasileiro.<\/p>\n<p style=\"text-align: justify;\">\u201cNo Brasil, temos o chamado encarceramento em massa.\u00a0\u00c9 o pa\u00eds no mundo que mais encarcera. Hoje em dia, os dados apontam que \u00e9 o terceiro pa\u00eds no mundo que tem mais pessoas encarceradas ou privadas de liberdade e est\u00e1 num crescente muito grande, contrariamente aos Estados Unidos, \u00e0 China ou \u00e0 R\u00fassia, que est\u00e3o num processo de desencarceramento, porque n\u00e3o acreditam que o c\u00e1rcere vai resolver problemas. E tamb\u00e9m n\u00f3s da Pastoral, como entidade da Igreja, n\u00e3o acreditamos.\u00a0O c\u00e1rcere \u00e9 um produtor de criminalidade, um produtor de viol\u00eancia, um produtor de tortura, n\u00f3s temos apresentado isto muito claramente com dados e isso tem tido repercuss\u00f5es, mas parece que n\u00e3o s\u00e3o suficientes para combater esta luta entre as fac\u00e7\u00f5es, sobretudo este\u00a0com\u00e9rcio que se tornou o sistema carcer\u00e1rio brasileiro\u201d, afirmou.<\/p>\n<p style=\"text-align: justify;\">Ainda segundo o Padre Gianfranco, \u201ccomo Igreja, como Pastoral, temos esta dimens\u00e3o que n\u00e3o \u00e9 apenas a da evangeliza\u00e7\u00e3o, no sentido de pregadores, mas \u00e9 sobretudo de\u00a0den\u00fancia, de querer o desencarceramento: esta \u00e9 a nossa batalha, este \u00e9 o nosso lema, o nosso trabalho, atrav\u00e9s de uma Agenda com dez pontos bem concretos, e que leva ao desencarceramento. Ela questiona pontos fundamentais como a quest\u00e3o das drogas, a quest\u00e3o de uma justi\u00e7a que \u00e9 vertical e n\u00e3o horizontal ou restaurativa, e com a responsabiliza\u00e7\u00e3o da pr\u00f3pria sociedade sobre os seus problemas, e o enfrentamento dos mesmos de uma forma coletiva e democr\u00e1tica\u201d.<\/p>\n<p style=\"text-align: justify;\">Com informa\u00e7\u00f5es e foto da Pastoral Carcer\u00e1ria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A morte de 56 presos no Complexo Penitenci\u00e1rio An\u00edsio Jobim, em Manaus (AM), no primeiro dia do ano, resultado de um dos maiores motins da hist\u00f3ria do sistema prisional brasileiro, gerou perplexidade em boa parte da sociedade brasileira. Infelizmente, o que se viu em Manaus acontece de forma recorrente pelo pa\u00eds: morte de presos quase&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"https:\/\/portalcatolico.net\/portal\/padre-gianfranco-encarceramento-em-massa-e-comercializacao-do-carcere-sao-os-principais-problemas\/\">Continue Reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":15441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-15440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques"],"_links":{"self":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/15440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/comments?post=15440"}],"version-history":[{"count":2,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/15440\/revisions"}],"predecessor-version":[{"id":15443,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/posts\/15440\/revisions\/15443"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/media\/15441"}],"wp:attachment":[{"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/media?parent=15440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/categories?post=15440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalcatolico.net\/portal\/wp-json\/wp\/v2\/tags?post=15440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}